{"id":206,"date":"2023-01-10T23:44:31","date_gmt":"2023-01-10T23:44:31","guid":{"rendered":"https:\/\/www.stbartholomews.lincs.sch.uk\/?page_id=206"},"modified":"2024-09-11T09:17:41","modified_gmt":"2024-09-11T09:17:41","slug":"learning-links","status":"publish","type":"page","link":"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/","title":{"rendered":"Learning Links"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"206\" class=\"elementor elementor-206\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b443ee1 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b443ee1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22c70676\" data-id=\"22c70676\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14738124 elementor-absolute elementor-hidden-phone elementor-widget__width-initial elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"14738124\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1058\" height=\"1058\" src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6.png\" class=\"attachment-full size-full wp-image-428\" alt=\"\" srcset=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6.png 1058w, https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6-300x300.png 300w, https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6-1024x1024.png 1024w, https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6-150x150.png 150w, https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6-768x768.png 768w\" sizes=\"(max-width: 1058px) 100vw, 1058px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-55d7d273 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55d7d273\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2cd631bd elementor-invisible\" data-id=\"2cd631bd\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7616a24e elementor-widget elementor-widget-heading\" data-id=\"7616a24e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">E-Safety<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-571bcb34 elementor-widget elementor-widget-text-editor\" data-id=\"571bcb34\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>The website below provides useful and up-to-date information about keeping safe on-line. Please ensure that you keep up-to-date with the latest guidance to keep your children safe.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7319f494 elementor-widget elementor-widget-text-editor\" data-id=\"7319f494\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>The Child Exploitation and Online Protection Centre (CEOP) is the UK&#8217;s national centre for online child protection. The CEOP Jump List gives you one click access to the latest CEOP news including Twitter, Facebook and YouTube updates as well as CEOP&#8217;s Most Wanted Alerts. The Jump List also has an alert when new content has been updated.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b594c66 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b594c66\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-07633ec\" data-id=\"07633ec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc63e5f eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"cc63e5f\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">CEOP<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.ceop.police.uk\/Safety-Centre\/\">\n                                                                                        Child Exploitation &amp; Online Protection                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfff008 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"bfff008\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">E-Safety Resources<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/03\/Esafety-Resources.pdf\">\n                                                                                        E-Safety Resources                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b0fe610\" data-id=\"b0fe610\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1ea950 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"e1ea950\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Wise Kids<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"http:\/\/www.wisekids.org.uk\/online_safety_tips_kids.htm\">\n                                                                                        Wise Kids                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a32022a eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"a32022a\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">CBBC<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.bbc.com\/ownit\">\n                                                                                        Staysafe                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3d267ec\" data-id=\"3d267ec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d17b259 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"d17b259\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Kids Smart<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.childnet.com\/resources\/looking-for-kidsmart\/\">\n                                                                                        Internet safety                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc5b00d eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"cc5b00d\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Childnet<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.childnet.com\/\">\n                                                                                        Internet Safety for Parents &amp; Children                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0d17cdd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d17cdd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1f96615\" data-id=\"1f96615\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68432d3 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"68432d3\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">NSPCC<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.nspcc.org.uk\/keeping-children-safe\/online-safety\/#guides\">\n                                                                                        Advice for parents in keeping children safe on the internet                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c011570\" data-id=\"c011570\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-344a490 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"344a490\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">NSPCC - Internet Safety on Mobile Devices<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.o2.co.uk\/help\/online-safety\">\n                                                                                        NSPCC - Internet Safety on Mobile Device                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8430269\" data-id=\"8430269\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4123773 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"4123773\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Barnado's<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.barnardos.org.uk\/blog\/tips-to-keep-your-child-safe-online\">\n                                                                                        Internet Safety Advice                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-40a7cce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40a7cce\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8ccb8c1 elementor-invisible\" data-id=\"8ccb8c1\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4ec06f elementor-widget elementor-widget-heading\" data-id=\"b4ec06f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Maths<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41a466f elementor-widget elementor-widget-text-editor\" data-id=\"41a466f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Numeracy is\u00a0<b>the knowledge, skills, behaviours and dispositions that students need in order to use mathematics in a wide range of situations<\/b>. It involves recognising and understanding the role of mathematics in the world and having the dispositions and capacities to use mathematical knowledge and skills purposefully.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-8feeae3 elementor-widget__width-auto elementor-absolute elementor-hidden-phone elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"8feeae3\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"64\" height=\"62\" data-src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Shape-1-copy-4.png\" class=\"attachment-large size-large wp-image-430 lazyload\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 64px; --smush-placeholder-aspect-ratio: 64\/62;\" \/><noscript><img decoding=\"async\" width=\"64\" height=\"62\" data-src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Shape-1-copy-4.png\" class=\"attachment-large size-large wp-image-430 lazyload\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 64px; --smush-placeholder-aspect-ratio: 64\/62;\" \/><noscript><img decoding=\"async\" width=\"64\" height=\"62\" data-src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Shape-1-copy-4.png\" class=\"attachment-large size-large wp-image-430 lazyload\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 64px; --smush-placeholder-aspect-ratio: 64\/62;\" \/><noscript><img decoding=\"async\" width=\"64\" height=\"62\" src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Shape-1-copy-4.png\" class=\"attachment-large size-large wp-image-430\" alt=\"\" \/><\/noscript><\/noscript><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38f6c5a0 elementor-widget__width-auto elementor-absolute elementor-hidden-phone elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"38f6c5a0\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"170\" height=\"180\" data-src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-1-copy-3.png\" class=\"attachment-large size-large wp-image-431 lazyload\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 170px; --smush-placeholder-aspect-ratio: 170\/180;\" \/><noscript><img decoding=\"async\" width=\"170\" height=\"180\" data-src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-1-copy-3.png\" class=\"attachment-large size-large wp-image-431 lazyload\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 170px; --smush-placeholder-aspect-ratio: 170\/180;\" \/><noscript><img decoding=\"async\" width=\"170\" height=\"180\" data-src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-1-copy-3.png\" class=\"attachment-large size-large wp-image-431 lazyload\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 170px; --smush-placeholder-aspect-ratio: 170\/180;\" \/><noscript><img decoding=\"async\" width=\"170\" height=\"180\" src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-1-copy-3.png\" class=\"attachment-large size-large wp-image-431\" alt=\"\" \/><\/noscript><\/noscript><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3498620 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3498620\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8279ed1\" data-id=\"8279ed1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-703f421 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"703f421\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Mathschase<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.mathschase.com\/\">\n                                                                                        Mathschase                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c967009\" data-id=\"c967009\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8faf95 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"c8faf95\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Number Twins<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.coolmathgames.com\/0-number-twins\/addition-practice-09.html\">\n                                                                                        Number Twins                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ddfc4f7\" data-id=\"ddfc4f7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd168a0 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"fd168a0\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">KS1 BBC Bitesize<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.bbc.co.uk\/bitesize\/subjects\/zjxhfg8\">\n                                                                                        KS1 BBC Bitesize                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c91c4f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c91c4f8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-bb8fdf2\" data-id=\"bb8fdf2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46feadb eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"46feadb\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">KS2 BBC Bitesize<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.bbc.co.uk\/bitesize\/subjects\/z826n39\">\n                                                                                        KS2 BBC Bitesize                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-10f3374\" data-id=\"10f3374\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa740fb eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"aa740fb\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">White Rose Maths<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/whiterosemaths.com\/advice-and-guidance\">\n                                                                                        White Rose Maths                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0ef524f\" data-id=\"0ef524f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f100dd eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"1f100dd\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Timetables Rockstars<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/ttrockstars.com\/\">\n                                                                                        Timetables Rockstars                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a738598 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a738598\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8c456ee\" data-id=\"8c456ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02eb10b eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"02eb10b\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Who wants to be a Mathionaire<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.mathsisfun.com\/games\/mathionaire-addition-quiz.html\">\n                                                                                        Who wants to be a Mathionaire                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c238a15\" data-id=\"c238a15\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e86c44 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"1e86c44\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Maths games for all ages<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/maths-games.org\/\">\n                                                                                        Maths games for all ages                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ea10bd7\" data-id=\"ea10bd7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bff53d9 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"bff53d9\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Maths Games Playground<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.mathplayground.com\/games.html\">\n                                                                                        Maths Games Playground                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4940822 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4940822\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-35d3484\" data-id=\"35d3484\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38979e4 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"38979e4\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Cool Maths for Kids<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.coolmath4kids.com\/\">\n                                                                                        Cool Maths for Kids                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-05ea313\" data-id=\"05ea313\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0f7fe2 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"e0f7fe2\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">ICT games to support maths<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/ictgames.com\/mobilePage\/index.html\">\n                                                                                        ICT games to support Maths                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3b620ab\" data-id=\"3b620ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53c3c38 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"53c3c38\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Top Marks maths practise<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.topmarks.co.uk\/maths-games\/5-7-years\/counting\">\n                                                                                        Top Marks maths practice                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a42cadf elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a42cadf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc136d1\" data-id=\"fc136d1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a8760c elementor-absolute elementor-hidden-phone elementor-widget__width-initial elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"3a8760c\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1058\" height=\"1058\" src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6.png\" class=\"attachment-full size-full wp-image-428\" alt=\"\" srcset=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6.png 1058w, https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6-300x300.png 300w, https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6-1024x1024.png 1024w, https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6-150x150.png 150w, https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6-768x768.png 768w\" sizes=\"(max-width: 1058px) 100vw, 1058px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7971137 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7971137\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-57a7562 elementor-invisible\" data-id=\"57a7562\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a606cb1 elementor-widget elementor-widget-heading\" data-id=\"a606cb1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">English<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-88f87df elementor-widget__width-auto elementor-absolute elementor-hidden-phone elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"88f87df\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"64\" height=\"62\" data-src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Shape-1-copy-4.png\" class=\"attachment-large size-large wp-image-430 lazyload\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 64px; --smush-placeholder-aspect-ratio: 64\/62;\" \/><noscript><img decoding=\"async\" width=\"64\" height=\"62\" data-src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Shape-1-copy-4.png\" class=\"attachment-large size-large wp-image-430 lazyload\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 64px; --smush-placeholder-aspect-ratio: 64\/62;\" \/><noscript><img decoding=\"async\" width=\"64\" height=\"62\" data-src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Shape-1-copy-4.png\" class=\"attachment-large size-large wp-image-430 lazyload\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 64px; --smush-placeholder-aspect-ratio: 64\/62;\" \/><noscript><img decoding=\"async\" width=\"64\" height=\"62\" src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Shape-1-copy-4.png\" class=\"attachment-large size-large wp-image-430\" alt=\"\" \/><\/noscript><\/noscript><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77468b0 elementor-widget__width-auto elementor-absolute elementor-hidden-phone elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"77468b0\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"170\" height=\"180\" data-src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-1-copy-3.png\" class=\"attachment-large size-large wp-image-431 lazyload\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 170px; --smush-placeholder-aspect-ratio: 170\/180;\" \/><noscript><img decoding=\"async\" width=\"170\" height=\"180\" data-src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-1-copy-3.png\" class=\"attachment-large size-large wp-image-431 lazyload\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 170px; --smush-placeholder-aspect-ratio: 170\/180;\" \/><noscript><img decoding=\"async\" width=\"170\" height=\"180\" data-src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-1-copy-3.png\" class=\"attachment-large size-large wp-image-431 lazyload\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 170px; --smush-placeholder-aspect-ratio: 170\/180;\" \/><noscript><img decoding=\"async\" width=\"170\" height=\"180\" src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-1-copy-3.png\" class=\"attachment-large size-large wp-image-431\" alt=\"\" \/><\/noscript><\/noscript><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dc33028 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dc33028\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4a08cf7\" data-id=\"4a08cf7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-068d12d eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"068d12d\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Pie Corbert's recommended reading list: Year Reception<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/03\/reception-1393132.pdf\">\n                                                                                        Reception                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5818ee9\" data-id=\"5818ee9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6177d3d eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"6177d3d\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Pie Corbert's recommended reading list: Year 1<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/03\/pie-corbett-yr1.pdf\">\n                                                                                        Year 1                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-76ed112\" data-id=\"76ed112\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f59483a eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"f59483a\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Pie Corbert's recommended reading list: Year 2<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/03\/pie-corbett-yr2.pdf\">\n                                                                                        Year 2                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-736a4a0\" data-id=\"736a4a0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfc7e3b eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"bfc7e3b\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Pie Corbert's recommended reading list: Year 3<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/03\/pie-corbett-yr3.pdf\">\n                                                                                        Year 3                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec643e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec643e8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5d404d4\" data-id=\"5d404d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d274dd9 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"d274dd9\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Pie Corbert's recommended reading list: Year 4<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/03\/pie-corbett-yr4.pdf\">\n                                                                                        Year 4                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-46fdb49\" data-id=\"46fdb49\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bee52b2 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"bee52b2\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Pie Corbert's recommended reading list: Year 5<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/03\/pie-corbett-yr5.pdf\">\n                                                                                        Year 5                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-aea33ac\" data-id=\"aea33ac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87f948f eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"87f948f\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Pie Corbert's recommended reading list: Year 6<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/03\/pie-corbett-yr6.pdf\">\n                                                                                        Year 6                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-527620d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"527620d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5b0c568\" data-id=\"5b0c568\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-120e9d7 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"120e9d7\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Top Marks<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.topmarks.co.uk\/english-games\">\n                                                                                        Top Marks                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5ff0a73\" data-id=\"5ff0a73\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b497933 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"b497933\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Primary Homework Help<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.primaryhomeworkhelp.co.uk\/literacy\/\">\n                                                                                        Primary Homework Help                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-eaa7dfb\" data-id=\"eaa7dfb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21652e2 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"21652e2\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Roy the Zebra<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.roythezebra.com\/english-ks1\/reading-games\/\">\n                                                                                        Roy the Zebra                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-d533073\" data-id=\"d533073\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-beb3761 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"beb3761\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">ICT Games<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/ictgames.com\/mobilePage\/literacy.html\">\n                                                                                        ICT Games                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-799e97b\" data-id=\"799e97b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26c67ab eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"26c67ab\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">KS2 - 7 of the Best Grammar Games<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.teachwire.net\/news\/7-of-the-best-online-grammar-games-for-ks2\/\">\n                                                                                        KS2 - 7 of the best grammar games                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b9c4950 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b9c4950\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6e4eaea\" data-id=\"6e4eaea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46f25c9 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"46f25c9\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Year R - Top 100 Recommended Reads<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/03\/Year-R-books.pdf\">\n                                                                                        Year R                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-101db77\" data-id=\"101db77\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9e1e70 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"f9e1e70\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Year 1 - Top 100 Recommended Reads<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/03\/Year-1-books.pdf\">\n                                                                                        Year 1                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f12457e\" data-id=\"f12457e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-445bacd eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"445bacd\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Year 2 - Top 100 Recommended Reads<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/03\/Year-2-Books.pdf\">\n                                                                                        Year 2                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1b22489\" data-id=\"1b22489\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70e2b77 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"70e2b77\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Year 3 - Top 100 Recommended Reads<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/03\/Year-3-Books.pdf\">\n                                                                                        Year 3                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6284ced elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6284ced\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-55d12ff\" data-id=\"55d12ff\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aaa702e eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"aaa702e\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Year 4 - Top 100 Recommended Reads<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/03\/Year-4-Books.pdf\">\n                                                                                        Year 4                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a701ab7\" data-id=\"a701ab7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bda0051 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"bda0051\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Year 5 - Top 100 Recommended Reads<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/03\/Year-5-books.pdf\">\n                                                                                        Year 5                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5edd9d3\" data-id=\"5edd9d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8afa29d eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"8afa29d\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Year 6 - Top 100 Recommended Reads<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/03\/Year-6-books.pdf\">\n                                                                                        Year 6                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f97414 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f97414\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ba2fba\" data-id=\"8ba2fba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-146d474 elementor-absolute elementor-hidden-phone elementor-widget__width-initial elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"146d474\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1058\" height=\"1058\" src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6.png\" class=\"attachment-full size-full wp-image-428\" alt=\"\" srcset=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6.png 1058w, https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6-300x300.png 300w, https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6-1024x1024.png 1024w, https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6-150x150.png 150w, https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6-768x768.png 768w\" sizes=\"(max-width: 1058px) 100vw, 1058px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9ca7140 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ca7140\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8fba340 elementor-invisible\" data-id=\"8fba340\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cc1027 elementor-widget elementor-widget-heading\" data-id=\"2cc1027\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Science & Topic<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ccbf8a elementor-widget__width-auto elementor-absolute elementor-hidden-phone elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"8ccbf8a\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"64\" height=\"62\" data-src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Shape-1-copy-4.png\" class=\"attachment-large size-large wp-image-430 lazyload\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 64px; --smush-placeholder-aspect-ratio: 64\/62;\" \/><noscript><img decoding=\"async\" width=\"64\" height=\"62\" data-src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Shape-1-copy-4.png\" class=\"attachment-large size-large wp-image-430 lazyload\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 64px; --smush-placeholder-aspect-ratio: 64\/62;\" \/><noscript><img decoding=\"async\" width=\"64\" height=\"62\" data-src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Shape-1-copy-4.png\" class=\"attachment-large size-large wp-image-430 lazyload\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 64px; --smush-placeholder-aspect-ratio: 64\/62;\" \/><noscript><img decoding=\"async\" width=\"64\" height=\"62\" src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Shape-1-copy-4.png\" class=\"attachment-large size-large wp-image-430\" alt=\"\" \/><\/noscript><\/noscript><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d35e26 elementor-widget__width-auto elementor-absolute elementor-hidden-phone elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"4d35e26\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"170\" height=\"180\" data-src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-1-copy-3.png\" class=\"attachment-large size-large wp-image-431 lazyload\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 170px; --smush-placeholder-aspect-ratio: 170\/180;\" \/><noscript><img decoding=\"async\" width=\"170\" height=\"180\" data-src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-1-copy-3.png\" class=\"attachment-large size-large wp-image-431 lazyload\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 170px; --smush-placeholder-aspect-ratio: 170\/180;\" \/><noscript><img decoding=\"async\" width=\"170\" height=\"180\" data-src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-1-copy-3.png\" class=\"attachment-large size-large wp-image-431 lazyload\" alt=\"\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 170px; --smush-placeholder-aspect-ratio: 170\/180;\" \/><noscript><img decoding=\"async\" width=\"170\" height=\"180\" src=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-1-copy-3.png\" class=\"attachment-large size-large wp-image-431\" alt=\"\" \/><\/noscript><\/noscript><\/noscript>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ab5353 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ab5353\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-0223529\" data-id=\"0223529\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a948ff eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"1a948ff\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Royal Society<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/royalsociety.org\/\">\n                                                                                        Royal Society                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-e73882c\" data-id=\"e73882c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c78e82c eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"c78e82c\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">BBC Science Clips<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.bbc.co.uk\/programmes\/b00hxp2v\/clips\">\n                                                                                        BBC Science Clips                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-90ef17c\" data-id=\"90ef17c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec94c91 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"ec94c91\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">BBC KS2 Bitesize Science<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.bbc.co.uk\/bitesize\/subjects\/z2pfb9q\">\n                                                                                        BBC KS2 Bitesize Science                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-f2143bc\" data-id=\"f2143bc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d48741 eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"0d48741\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Primary Homework Help<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"http:\/\/www.primaryhomeworkhelp.co.uk\/\">\n                                                                                        Primary Homework Help                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-64af7a9\" data-id=\"64af7a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e937cf eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"5e937cf\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-left eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                                                                                                        <\/div>\n                                                                        <h2 class=\"eael-elements-flip-box-heading\">Science Kids<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n\t                                                                            <p><\/p>                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon far fa-arrow-alt-circle-down\"><\/i>                                                <\/div>\n                                                                                                            <h2 class=\"eael-elements-flip-box-heading\">Download now<\/h2>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                                                                <p><\/p>                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/www.sciencekids.co.nz\/gamesactivities.html\">\n                                                                                        Science Games                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>E-Safety The website below provides useful and up-to-date information about keeping safe on-line. Please ensure that you keep up-to-date with the latest guidance to keep your children safe. The Child [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-206","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Learning Links - St Bartholomew&#039;s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Learning Links - St Bartholomew&#039;s\" \/>\n<meta property=\"og:description\" content=\"E-Safety The website below provides useful and up-to-date information about keeping safe on-line. Please ensure that you keep up-to-date with the latest guidance to keep your children safe. The Child [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/\" \/>\n<meta property=\"og:site_name\" content=\"St Bartholomew&#039;s\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/StBartholomewsCEPrimarySchool\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-11T09:17:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@stbarts5\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/\",\"url\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/\",\"name\":\"Learning Links - St Bartholomew&#039;s\",\"isPartOf\":{\"@id\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6.png\",\"datePublished\":\"2023-01-10T23:44:31+00:00\",\"dateModified\":\"2024-09-11T09:17:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/#primaryimage\",\"url\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6.png\",\"contentUrl\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6.png\",\"width\":1058,\"height\":1058},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Learning Links\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/#website\",\"url\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/\",\"name\":\"St Bartholomew&#039;s\",\"description\":\"St Bartholomew&#039;s primary school\",\"publisher\":{\"@id\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/#organization\",\"name\":\"St Bartholomew&#039;s\",\"url\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2022\/10\/LOGOpng.png\",\"contentUrl\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2022\/10\/LOGOpng.png\",\"width\":1419,\"height\":1304,\"caption\":\"St Bartholomew&#039;s\"},\"image\":{\"@id\":\"https:\/\/www.stbartholomews.lincs.sch.uk\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/StBartholomewsCEPrimarySchool\/\",\"https:\/\/x.com\/stbarts5\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Learning Links - St Bartholomew&#039;s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/","og_locale":"en_US","og_type":"article","og_title":"Learning Links - St Bartholomew&#039;s","og_description":"E-Safety The website below provides useful and up-to-date information about keeping safe on-line. Please ensure that you keep up-to-date with the latest guidance to keep your children safe. The Child [&hellip;]","og_url":"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/","og_site_name":"St Bartholomew&#039;s","article_publisher":"https:\/\/www.facebook.com\/StBartholomewsCEPrimarySchool\/","article_modified_time":"2024-09-11T09:17:41+00:00","og_image":[{"url":"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6.png"}],"twitter_card":"summary_large_image","twitter_site":"@stbarts5","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/","url":"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/","name":"Learning Links - St Bartholomew&#039;s","isPartOf":{"@id":"https:\/\/www.stbartholomews.lincs.sch.uk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/#primaryimage"},"image":{"@id":"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/#primaryimage"},"thumbnailUrl":"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6.png","datePublished":"2023-01-10T23:44:31+00:00","dateModified":"2024-09-11T09:17:41+00:00","breadcrumb":{"@id":"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/#primaryimage","url":"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6.png","contentUrl":"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2023\/01\/Group-6.png","width":1058,"height":1058},{"@type":"BreadcrumbList","@id":"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/learning-links\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.stbartholomews.lincs.sch.uk\/"},{"@type":"ListItem","position":2,"name":"Learning Links"}]},{"@type":"WebSite","@id":"https:\/\/www.stbartholomews.lincs.sch.uk\/#website","url":"https:\/\/www.stbartholomews.lincs.sch.uk\/","name":"St Bartholomew&#039;s","description":"St Bartholomew&#039;s primary school","publisher":{"@id":"https:\/\/www.stbartholomews.lincs.sch.uk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.stbartholomews.lincs.sch.uk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.stbartholomews.lincs.sch.uk\/#organization","name":"St Bartholomew&#039;s","url":"https:\/\/www.stbartholomews.lincs.sch.uk\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.stbartholomews.lincs.sch.uk\/#\/schema\/logo\/image\/","url":"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2022\/10\/LOGOpng.png","contentUrl":"https:\/\/www.stbartholomews.lincs.sch.uk\/wp-content\/uploads\/2022\/10\/LOGOpng.png","width":1419,"height":1304,"caption":"St Bartholomew&#039;s"},"image":{"@id":"https:\/\/www.stbartholomews.lincs.sch.uk\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/StBartholomewsCEPrimarySchool\/","https:\/\/x.com\/stbarts5"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:40:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":""},"_links":{"self":[{"href":"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/wp-json\/wp\/v2\/pages\/206"}],"collection":[{"href":"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/wp-json\/wp\/v2\/comments?post=206"}],"version-history":[{"count":718,"href":"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/wp-json\/wp\/v2\/pages\/206\/revisions"}],"predecessor-version":[{"id":5554,"href":"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/wp-json\/wp\/v2\/pages\/206\/revisions\/5554"}],"wp:attachment":[{"href":"https:\/\/www.stbartholomews.lincs.sch.uk\/index.php\/wp-json\/wp\/v2\/media?parent=206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}